{"id":2538,"date":"2025-02-07T14:46:58","date_gmt":"2025-02-07T14:46:58","guid":{"rendered":"https:\/\/opera.krescendo.it\/?post_type=product&#038;p=2538"},"modified":"2025-07-29T14:47:09","modified_gmt":"2025-07-29T14:47:09","slug":"art-05203a-detecteur-combine-de-chaleur-et-de-fumee","status":"publish","type":"product","link":"https:\/\/www.opera-access.it\/fr\/produit\/art-05203a-detecteur-combine-de-chaleur-et-de-fumee\/","title":{"rendered":"Art. 05203A \/ 05203ABRA - D\u00e9tecteur combin\u00e9 de chaleur et de fum\u00e9e"},"content":{"rendered":"<p>Bo\u00eete en ABS blanc.  Article disponible en deux versions : l'une pouvant \u00eatre connect\u00e9e au <em>Op\u00e9ra central 52002<\/em>: [<strong>05203A<\/strong>et celles qui peuvent \u00eatre connect\u00e9es \u00e0 d'autres centrales \u00e9lectriques <em>pas d'Op\u00e9ra<\/em>: [<strong>05203A + BRA<\/strong>].<\/p>","protected":false},"excerpt":{"rendered":"<p>Accessoires pour l'installation de syst\u00e8mes de protection contre l'incendie conform\u00e9ment \u00e0 la norme EN54.<\/p>\n<p>&nbsp;<\/p>","protected":false},"featured_media":2543,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_cat":[22,74],"product_tag":[102],"class_list":["post-2538","product","type-product","status-publish","has-post-thumbnail","product_cat-fire-control","product_cat-centrale-fire","product_tag-centrale-antincendio","first","instock","featured","shipping-taxable","product-type-simple"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Accessori per l&#039;installazione di impianti antincendio secondo la normativa EN54.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.opera-access.it\/fr\/produit\/art-05203a-detecteur-combine-de-chaleur-et-de-fumee\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Opera - Operating Access - Elettroserrature, serrature motorizzate, fermi elettromagnetici, controllo accessi\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Art. 05203A \/ 05203ABRA \u2013 Rilevatore combinato di calore e fumo - Opera - Operating Access\" \/>\n\t\t<meta property=\"og:description\" content=\"Accessori per l&#039;installazione di impianti antincendio secondo la normativa EN54.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.opera-access.it\/fr\/produit\/art-05203a-detecteur-combine-de-chaleur-et-de-fumee\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.opera-access.it\/wp-content\/uploads\/2024\/04\/RED_8497.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.opera-access.it\/wp-content\/uploads\/2024\/04\/RED_8497.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-02-07T14:46:58+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-07-29T14:47:09+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/opera.elettroserrature\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Art. 05203A \/ 05203ABRA \u2013 Rilevatore combinato di calore e fumo - Opera - Operating Access\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Accessori per l&#039;installazione di impianti antincendio secondo la normativa EN54.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.opera-access.it\/wp-content\/uploads\/2024\/04\/RED_8497.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/fr\\\/produit\\\/art-05203a-detecteur-combine-de-chaleur-et-de-fumee\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/fr#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.opera-access.it\\\/fr\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/fr\\\/boutique\\\/#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/fr\\\/boutique\\\/#listItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.opera-access.it\\\/fr\\\/boutique\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/fr\\\/product-category\\\/controle-des-incendies\\\/#listItem\",\"name\":\"Fire Control\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/fr#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/fr\\\/product-category\\\/controle-des-incendies\\\/#listItem\",\"position\":3,\"name\":\"Fire Control\",\"item\":\"https:\\\/\\\/www.opera-access.it\\\/fr\\\/product-category\\\/controle-des-incendies\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/fr\\\/product-category\\\/controle-des-incendies\\\/caserne-de-pompiers\\\/#listItem\",\"name\":\"Centrale Fire\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/fr\\\/boutique\\\/#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/fr\\\/product-category\\\/controle-des-incendies\\\/caserne-de-pompiers\\\/#listItem\",\"position\":4,\"name\":\"Centrale Fire\",\"item\":\"https:\\\/\\\/www.opera-access.it\\\/fr\\\/product-category\\\/controle-des-incendies\\\/caserne-de-pompiers\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/fr\\\/produit\\\/art-05203a-detecteur-combine-de-chaleur-et-de-fumee\\\/#listItem\",\"name\":\"Art. 05203A \\\/ 05203ABRA &#8211; Rilevatore combinato di calore e fumo\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/fr\\\/product-category\\\/controle-des-incendies\\\/#listItem\",\"name\":\"Fire Control\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/fr\\\/produit\\\/art-05203a-detecteur-combine-de-chaleur-et-de-fumee\\\/#listItem\",\"position\":5,\"name\":\"Art. 05203A \\\/ 05203ABRA &#8211; Rilevatore combinato di calore e fumo\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/fr\\\/product-category\\\/controle-des-incendies\\\/caserne-de-pompiers\\\/#listItem\",\"name\":\"Centrale Fire\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/fr\\\/produit\\\/art-05203a-detecteur-combine-de-chaleur-et-de-fumee\\\/#itempage\",\"url\":\"https:\\\/\\\/www.opera-access.it\\\/fr\\\/produit\\\/art-05203a-detecteur-combine-de-chaleur-et-de-fumee\\\/\",\"name\":\"Art. 05203A \\\/ 05203ABRA \\u2013 Rilevatore combinato di calore e fumo - Opera - Operating Access\",\"description\":\"Accessori per l'installazione di impianti antincendio secondo la normativa EN54.\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/fr\\\/produit\\\/art-05203a-detecteur-combine-de-chaleur-et-de-fumee\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.opera-access.it\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/05203A.jpg\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/fr\\\/produit\\\/art-05203a-detecteur-combine-de-chaleur-et-de-fumee\\\/#mainImage\",\"width\":1200,\"height\":1000},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/fr\\\/produit\\\/art-05203a-detecteur-combine-de-chaleur-et-de-fumee\\\/#mainImage\"},\"datePublished\":\"2025-02-07T14:46:58+00:00\",\"dateModified\":\"2025-07-29T14:47:09+00:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/fr\\\/#organization\",\"name\":\"Opera - Operating Access\",\"description\":\"Elettroserrature, serrature motorizzate, fermi elettromagnetici, controllo accessi\",\"url\":\"https:\\\/\\\/www.opera-access.it\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.opera-access.it\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/OPERA_logo_WEB.svg\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/fr\\\/produit\\\/art-05203a-detecteur-combine-de-chaleur-et-de-fumee\\\/#organizationLogo\",\"width\":674,\"height\":172},\"image\":{\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/fr\\\/produit\\\/art-05203a-detecteur-combine-de-chaleur-et-de-fumee\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/opera.elettroserrature\\\/\",\"https:\\\/\\\/www.instagram.com\\\/operasrl_italy\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCqDsBsvzX9q1PVTLxOfCm-A\\\/videos?view_as=subscriber\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/opera---locks\\\/?viewAsMember=true\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.opera-access.it\\\/fr\\\/\",\"name\":\"Opera - Operating Access\",\"description\":\"Elettroserrature, serrature motorizzate, fermi elettromagnetici, controllo accessi\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Art. 05203A \/ 05203ABRA \u2013 Rilevatore combinato di calore e fumo - Opera - Operating Access","description":"Accessori per l'installazione di impianti antincendio secondo la normativa EN54.","canonical_url":"https:\/\/www.opera-access.it\/fr\/produit\/art-05203a-detecteur-combine-de-chaleur-et-de-fumee\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.opera-access.it\/fr\/produit\/art-05203a-detecteur-combine-de-chaleur-et-de-fumee\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/fr#listItem","position":1,"name":"Home","item":"https:\/\/www.opera-access.it\/fr","nextItem":{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/fr\/boutique\/#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/fr\/boutique\/#listItem","position":2,"name":"Shop","item":"https:\/\/www.opera-access.it\/fr\/boutique\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/fr\/product-category\/controle-des-incendies\/#listItem","name":"Fire Control"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/fr#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/fr\/product-category\/controle-des-incendies\/#listItem","position":3,"name":"Fire Control","item":"https:\/\/www.opera-access.it\/fr\/product-category\/controle-des-incendies\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/fr\/product-category\/controle-des-incendies\/caserne-de-pompiers\/#listItem","name":"Centrale Fire"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/fr\/boutique\/#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/fr\/product-category\/controle-des-incendies\/caserne-de-pompiers\/#listItem","position":4,"name":"Centrale Fire","item":"https:\/\/www.opera-access.it\/fr\/product-category\/controle-des-incendies\/caserne-de-pompiers\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/fr\/produit\/art-05203a-detecteur-combine-de-chaleur-et-de-fumee\/#listItem","name":"Art. 05203A \/ 05203ABRA &#8211; Rilevatore combinato di calore e fumo"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/fr\/product-category\/controle-des-incendies\/#listItem","name":"Fire Control"}},{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/fr\/produit\/art-05203a-detecteur-combine-de-chaleur-et-de-fumee\/#listItem","position":5,"name":"Art. 05203A \/ 05203ABRA &#8211; Rilevatore combinato di calore e fumo","previousItem":{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/fr\/product-category\/controle-des-incendies\/caserne-de-pompiers\/#listItem","name":"Centrale Fire"}}]},{"@type":"ItemPage","@id":"https:\/\/www.opera-access.it\/fr\/produit\/art-05203a-detecteur-combine-de-chaleur-et-de-fumee\/#itempage","url":"https:\/\/www.opera-access.it\/fr\/produit\/art-05203a-detecteur-combine-de-chaleur-et-de-fumee\/","name":"Art. 05203A \/ 05203ABRA \u2013 Rilevatore combinato di calore e fumo - Opera - Operating Access","description":"Accessori per l'installazione di impianti antincendio secondo la normativa EN54.","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/www.opera-access.it\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/www.opera-access.it\/fr\/produit\/art-05203a-detecteur-combine-de-chaleur-et-de-fumee\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.opera-access.it\/wp-content\/uploads\/2025\/02\/05203A.jpg","@id":"https:\/\/www.opera-access.it\/fr\/produit\/art-05203a-detecteur-combine-de-chaleur-et-de-fumee\/#mainImage","width":1200,"height":1000},"primaryImageOfPage":{"@id":"https:\/\/www.opera-access.it\/fr\/produit\/art-05203a-detecteur-combine-de-chaleur-et-de-fumee\/#mainImage"},"datePublished":"2025-02-07T14:46:58+00:00","dateModified":"2025-07-29T14:47:09+00:00"},{"@type":"Organization","@id":"https:\/\/www.opera-access.it\/fr\/#organization","name":"Opera - Operating Access","description":"Elettroserrature, serrature motorizzate, fermi elettromagnetici, controllo accessi","url":"https:\/\/www.opera-access.it\/fr\/","logo":{"@type":"ImageObject","url":"https:\/\/www.opera-access.it\/wp-content\/uploads\/2024\/04\/OPERA_logo_WEB.svg","@id":"https:\/\/www.opera-access.it\/fr\/produit\/art-05203a-detecteur-combine-de-chaleur-et-de-fumee\/#organizationLogo","width":674,"height":172},"image":{"@id":"https:\/\/www.opera-access.it\/fr\/produit\/art-05203a-detecteur-combine-de-chaleur-et-de-fumee\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/opera.elettroserrature\/","https:\/\/www.instagram.com\/operasrl_italy\/","https:\/\/www.youtube.com\/channel\/UCqDsBsvzX9q1PVTLxOfCm-A\/videos?view_as=subscriber","https:\/\/www.linkedin.com\/company\/opera---locks\/?viewAsMember=true"]},{"@type":"WebSite","@id":"https:\/\/www.opera-access.it\/fr\/#website","url":"https:\/\/www.opera-access.it\/fr\/","name":"Opera - Operating Access","description":"Elettroserrature, serrature motorizzate, fermi elettromagnetici, controllo accessi","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/www.opera-access.it\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Opera - Operating Access - Elettroserrature, serrature motorizzate, fermi elettromagnetici, controllo accessi","og:type":"article","og:title":"Art. 05203A \/ 05203ABRA \u2013 Rilevatore combinato di calore e fumo - Opera - Operating Access","og:description":"Accessori per l'installazione di impianti antincendio secondo la normativa EN54.","og:url":"https:\/\/www.opera-access.it\/fr\/produit\/art-05203a-detecteur-combine-de-chaleur-et-de-fumee\/","og:image":"https:\/\/www.opera-access.it\/wp-content\/uploads\/2024\/04\/RED_8497.jpg","og:image:secure_url":"https:\/\/www.opera-access.it\/wp-content\/uploads\/2024\/04\/RED_8497.jpg","og:image:width":1920,"og:image:height":1280,"article:published_time":"2025-02-07T14:46:58+00:00","article:modified_time":"2025-07-29T14:47:09+00:00","article:publisher":"https:\/\/www.facebook.com\/opera.elettroserrature\/","twitter:card":"summary_large_image","twitter:title":"Art. 05203A \/ 05203ABRA \u2013 Rilevatore combinato di calore e fumo - Opera - Operating Access","twitter:description":"Accessori per l'installazione di impianti antincendio secondo la normativa EN54.","twitter:image":"https:\/\/www.opera-access.it\/wp-content\/uploads\/2024\/04\/RED_8497.jpg"},"aioseo_meta_data":{"post_id":"2538","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"ItemPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-06-09 14:22:28","updated":"2025-07-29 15:01:42","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.opera-access.it\/fr\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.opera-access.it\/fr\/boutique\/\" title=\"Shop\">Shop<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.opera-access.it\/fr\/product-category\/controle-des-incendies\/\" title=\"Fire Control\">Fire Control<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.opera-access.it\/fr\/product-category\/controle-des-incendies\/caserne-de-pompiers\/\" title=\"Centrale Fire\">Centrale Fire<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tArt. 05203A \/ 05203ABRA \u2013 Rilevatore combinato di calore e fumo\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.opera-access.it\/fr"},{"label":"Shop","link":"https:\/\/www.opera-access.it\/fr\/boutique\/"},{"label":"Fire Control","link":"https:\/\/www.opera-access.it\/fr\/product-category\/controle-des-incendies\/"},{"label":"Centrale Fire","link":"https:\/\/www.opera-access.it\/fr\/product-category\/controle-des-incendies\/caserne-de-pompiers\/"},{"label":"Art. 05203A \/ 05203ABRA &#8211; Rilevatore combinato di calore e fumo","link":"https:\/\/www.opera-access.it\/fr\/produit\/art-05203a-detecteur-combine-de-chaleur-et-de-fumee\/"}],"_links":{"self":[{"href":"https:\/\/www.opera-access.it\/fr\/wp-json\/wp\/v2\/product\/2538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opera-access.it\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.opera-access.it\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opera-access.it\/fr\/wp-json\/wp\/v2\/media\/2543"}],"wp:attachment":[{"href":"https:\/\/www.opera-access.it\/fr\/wp-json\/wp\/v2\/media?parent=2538"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.opera-access.it\/fr\/wp-json\/wp\/v2\/product_cat?post=2538"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.opera-access.it\/fr\/wp-json\/wp\/v2\/product_tag?post=2538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}