{"id":8027,"date":"2025-03-24T10:34:16","date_gmt":"2025-03-24T10:34:16","guid":{"rendered":"https:\/\/opera.krescendo.it\/?post_type=product&#038;p=8027"},"modified":"2025-10-02T13:08:19","modified_gmt":"2025-10-02T13:08:19","slug":"art-26600-26608-perno-solenoide-de-seguridad-para-enclavamiento","status":"publish","type":"product","link":"https:\/\/www.opera-access.it\/es\/product\/art-26600-26608-perno-solenoide-de-seguridad-para-enclavamiento\/","title":{"rendered":"Art. 26600 \/ 26608 \u2013 Pasador de seguridad horizontal con solenoide para interbloqueo \u2013 Abierto en ausencia de corriente"},"content":{"rendered":"<p>Cerrojo magn\u00e9tico con placa de cierre y placa de armadura de acero inoxidable y cerrojo giratorio anticorte de acero templado [<strong>26600 \/ 26608<\/strong>].<\/p>","protected":false},"excerpt":{"rendered":"<p>Cerrojo de solenoide de banda de seguridad para uso intensivo y continuo, con inserci\u00f3n en la hoja, para puertas de aluminio o acero en configuraci\u00f3n simple (bloques de pisos, oficinas, empresas...) o con enclavamiento (bancos, joyer\u00edas, instituciones...), combinable con interfonos y sistemas de control de acceso. Frontal y contraplaca de acero inoxidable (con contraplaca equipada con im\u00e1n de alineaci\u00f3n) y cerrojo giratorio de acero endurecido, anticorte y antirrobo, con bloqueo mec\u00e1nico en posici\u00f3n cerrada. Apertura en ausencia de alimentaci\u00f3n el\u00e9ctrica. Equipada con electr\u00f3nica de control interna por microprocesador y conector de conexi\u00f3n r\u00e1pida, apertura mec\u00e1nica con cilindro europeo o manilla y reconexi\u00f3n autom\u00e1tica con temporizaci\u00f3n ajustable (temporizaci\u00f3n desconectable para el uso del cerrojo electromagn\u00e9tico con electr\u00f3nica de control externa).<\/p>\n<p>Nota: el cilindro con forma de perfil europeo puede adquirirse por separado.<\/p>","protected":false},"featured_media":8131,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_cat":[67,28],"product_tag":[],"class_list":["post-8027","product","type-product","status-publish","has-post-thumbnail","product_cat-classica","product_cat-serie-classica","first","instock","featured","shipping-taxable","purchasable","product-type-variable"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Elettropistone di sicurezza da fascia per uso intensivo e continuativo, con inserimento sull&#039;anta, per porte in alluminio o acciaio in configurazione singola (condomini, uffici, aziende...) o interbloccate (banche, gioiellerie, enti...), abbinabile a citofoni e a sistemi per controllo accessi. Frontale e contropiastra in acciaio inox (con contropiastra dotata di magnete di allineamento) e catenaccio rotante in acciaio temprato antitaglio e antieffrazione, con blocco meccanico in posizione di chiusura. Aperto in assenza di alimentazione. \u00c8 dotato di elettronica di gestione interna a microprocessore e connettore ad innesto rapido per il collegamento, apertura meccanica con cilindro europeo o maniglia e richiusura automatica con temporizzazioni regolabili (le temporizzazioni sono disinseribili per l\u2019utilizzo dell\u2019elettropistone con elettroniche di gestione esterne). N.B.: il cilindro sagomato a profilo europeo \u00e8 acquistabile separatamente.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.opera-access.it\/es\/product\/art-26600-26608-perno-solenoide-de-seguridad-para-enclavamiento\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Opera - Operating Access - Elettroserrature, serrature motorizzate, fermi elettromagnetici, controllo accessi\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Art. 26600 \/ 26608 \u2013 Elettropistone di sicurezza orizzontale per interblocco \u2013 Aperto in assenza di corrente - Opera - Operating Access\" \/>\n\t\t<meta property=\"og:description\" content=\"Elettropistone di sicurezza da fascia per uso intensivo e continuativo, con inserimento sull&#039;anta, per porte in alluminio o acciaio in configurazione singola (condomini, uffici, aziende...) o interbloccate (banche, gioiellerie, enti...), abbinabile a citofoni e a sistemi per controllo accessi. Frontale e contropiastra in acciaio inox (con contropiastra dotata di magnete di allineamento) e catenaccio rotante in acciaio temprato antitaglio e antieffrazione, con blocco meccanico in posizione di chiusura. Aperto in assenza di alimentazione. \u00c8 dotato di elettronica di gestione interna a microprocessore e connettore ad innesto rapido per il collegamento, apertura meccanica con cilindro europeo o maniglia e richiusura automatica con temporizzazioni regolabili (le temporizzazioni sono disinseribili per l\u2019utilizzo dell\u2019elettropistone con elettroniche di gestione esterne). N.B.: il cilindro sagomato a profilo europeo \u00e8 acquistabile separatamente.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.opera-access.it\/es\/product\/art-26600-26608-perno-solenoide-de-seguridad-para-enclavamiento\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.opera-access.it\/wp-content\/uploads\/2024\/04\/RED_8497.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.opera-access.it\/wp-content\/uploads\/2024\/04\/RED_8497.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-03-24T10:34:16+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-10-02T13:08:19+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/opera.elettroserrature\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Art. 26600 \/ 26608 \u2013 Elettropistone di sicurezza orizzontale per interblocco \u2013 Aperto in assenza di corrente - Opera - Operating Access\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Elettropistone di sicurezza da fascia per uso intensivo e continuativo, con inserimento sull&#039;anta, per porte in alluminio o acciaio in configurazione singola (condomini, uffici, aziende...) o interbloccate (banche, gioiellerie, enti...), abbinabile a citofoni e a sistemi per controllo accessi. Frontale e contropiastra in acciaio inox (con contropiastra dotata di magnete di allineamento) e catenaccio rotante in acciaio temprato antitaglio e antieffrazione, con blocco meccanico in posizione di chiusura. Aperto in assenza di alimentazione. \u00c8 dotato di elettronica di gestione interna a microprocessore e connettore ad innesto rapido per il collegamento, apertura meccanica con cilindro europeo o maniglia e richiusura automatica con temporizzazioni regolabili (le temporizzazioni sono disinseribili per l\u2019utilizzo dell\u2019elettropistone con elettroniche di gestione esterne). N.B.: il cilindro sagomato a profilo europeo \u00e8 acquistabile separatamente.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.opera-access.it\/wp-content\/uploads\/2024\/04\/RED_8497.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/es\\\/product\\\/art-26600-26608-perno-solenoide-de-seguridad-para-enclavamiento\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/es#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.opera-access.it\\\/es\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/es\\\/tienda\\\/#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/es\\\/tienda\\\/#listItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.opera-access.it\\\/es\\\/tienda\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/es\\\/product-category\\\/serie-clasica\\\/#listItem\",\"name\":\"Serie Classica\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/es#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/es\\\/product-category\\\/serie-clasica\\\/#listItem\",\"position\":3,\"name\":\"Serie Classica\",\"item\":\"https:\\\/\\\/www.opera-access.it\\\/es\\\/product-category\\\/serie-clasica\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/es\\\/product-category\\\/serie-clasica\\\/clasico\\\/#listItem\",\"name\":\"Classica\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/es\\\/tienda\\\/#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/es\\\/product-category\\\/serie-clasica\\\/clasico\\\/#listItem\",\"position\":4,\"name\":\"Classica\",\"item\":\"https:\\\/\\\/www.opera-access.it\\\/es\\\/product-category\\\/serie-clasica\\\/clasico\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/es\\\/product\\\/art-26600-26608-perno-solenoide-de-seguridad-para-enclavamiento\\\/#listItem\",\"name\":\"Art. 26600 \\\/ 26608 &#8211; Elettropistone di sicurezza orizzontale per interblocco &#8211; Aperto in assenza di corrente\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/es\\\/product-category\\\/serie-clasica\\\/#listItem\",\"name\":\"Serie Classica\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/es\\\/product\\\/art-26600-26608-perno-solenoide-de-seguridad-para-enclavamiento\\\/#listItem\",\"position\":5,\"name\":\"Art. 26600 \\\/ 26608 &#8211; Elettropistone di sicurezza orizzontale per interblocco &#8211; Aperto in assenza di corrente\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/es\\\/product-category\\\/serie-clasica\\\/clasico\\\/#listItem\",\"name\":\"Classica\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/es\\\/product\\\/art-26600-26608-perno-solenoide-de-seguridad-para-enclavamiento\\\/#itempage\",\"url\":\"https:\\\/\\\/www.opera-access.it\\\/es\\\/product\\\/art-26600-26608-perno-solenoide-de-seguridad-para-enclavamiento\\\/\",\"name\":\"Art. 26600 \\\/ 26608 \\u2013 Elettropistone di sicurezza orizzontale per interblocco \\u2013 Aperto in assenza di corrente - Opera - Operating Access\",\"description\":\"Elettropistone di sicurezza da fascia per uso intensivo e continuativo, con inserimento sull'anta, per porte in alluminio o acciaio in configurazione singola (condomini, uffici, aziende...) o interbloccate (banche, gioiellerie, enti...), abbinabile a citofoni e a sistemi per controllo accessi. Frontale e contropiastra in acciaio inox (con contropiastra dotata di magnete di allineamento) e catenaccio rotante in acciaio temprato antitaglio e antieffrazione, con blocco meccanico in posizione di chiusura. Aperto in assenza di alimentazione. \\u00c8 dotato di elettronica di gestione interna a microprocessore e connettore ad innesto rapido per il collegamento, apertura meccanica con cilindro europeo o maniglia e richiusura automatica con temporizzazioni regolabili (le temporizzazioni sono disinseribili per l\\u2019utilizzo dell\\u2019elettropistone con elettroniche di gestione esterne). N.B.: il cilindro sagomato a profilo europeo \\u00e8 acquistabile separatamente.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/es\\\/product\\\/art-26600-26608-perno-solenoide-de-seguridad-para-enclavamiento\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.opera-access.it\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/27600.jpg\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/es\\\/product\\\/art-26600-26608-perno-solenoide-de-seguridad-para-enclavamiento\\\/#mainImage\",\"width\":1200,\"height\":1000},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/es\\\/product\\\/art-26600-26608-perno-solenoide-de-seguridad-para-enclavamiento\\\/#mainImage\"},\"datePublished\":\"2025-03-24T10:34:16+00:00\",\"dateModified\":\"2025-10-02T13:08:19+00:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/es\\\/#organization\",\"name\":\"Opera - Operating Access\",\"description\":\"Elettroserrature, serrature motorizzate, fermi elettromagnetici, controllo accessi\",\"url\":\"https:\\\/\\\/www.opera-access.it\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.opera-access.it\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/OPERA_logo_WEB.svg\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/es\\\/product\\\/art-26600-26608-perno-solenoide-de-seguridad-para-enclavamiento\\\/#organizationLogo\",\"width\":674,\"height\":172},\"image\":{\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/es\\\/product\\\/art-26600-26608-perno-solenoide-de-seguridad-para-enclavamiento\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/opera.elettroserrature\\\/\",\"https:\\\/\\\/www.instagram.com\\\/operasrl_italy\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCqDsBsvzX9q1PVTLxOfCm-A\\\/videos?view_as=subscriber\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/opera---locks\\\/?viewAsMember=true\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.opera-access.it\\\/es\\\/\",\"name\":\"Opera - Operating Access\",\"description\":\"Elettroserrature, serrature motorizzate, fermi elettromagnetici, controllo accessi\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Art. 26600 \/ 26608 \u2013 Elettropistone di sicurezza orizzontale per interblocco \u2013 Aperto in assenza di corrente - Opera - Operating Access","description":"Elettropistone di sicurezza da fascia per uso intensivo e continuativo, con inserimento sull'anta, per porte in alluminio o acciaio in configurazione singola (condomini, uffici, aziende...) o interbloccate (banche, gioiellerie, enti...), abbinabile a citofoni e a sistemi per controllo accessi. Frontale e contropiastra in acciaio inox (con contropiastra dotata di magnete di allineamento) e catenaccio rotante in acciaio temprato antitaglio e antieffrazione, con blocco meccanico in posizione di chiusura. Aperto in assenza di alimentazione. \u00c8 dotato di elettronica di gestione interna a microprocessore e connettore ad innesto rapido per il collegamento, apertura meccanica con cilindro europeo o maniglia e richiusura automatica con temporizzazioni regolabili (le temporizzazioni sono disinseribili per l\u2019utilizzo dell\u2019elettropistone con elettroniche di gestione esterne). N.B.: il cilindro sagomato a profilo europeo \u00e8 acquistabile separatamente.","canonical_url":"https:\/\/www.opera-access.it\/es\/product\/art-26600-26608-perno-solenoide-de-seguridad-para-enclavamiento\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.opera-access.it\/es\/product\/art-26600-26608-perno-solenoide-de-seguridad-para-enclavamiento\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/es#listItem","position":1,"name":"Home","item":"https:\/\/www.opera-access.it\/es","nextItem":{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/es\/tienda\/#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/es\/tienda\/#listItem","position":2,"name":"Shop","item":"https:\/\/www.opera-access.it\/es\/tienda\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/es\/product-category\/serie-clasica\/#listItem","name":"Serie Classica"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/es#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/es\/product-category\/serie-clasica\/#listItem","position":3,"name":"Serie Classica","item":"https:\/\/www.opera-access.it\/es\/product-category\/serie-clasica\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/es\/product-category\/serie-clasica\/clasico\/#listItem","name":"Classica"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/es\/tienda\/#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/es\/product-category\/serie-clasica\/clasico\/#listItem","position":4,"name":"Classica","item":"https:\/\/www.opera-access.it\/es\/product-category\/serie-clasica\/clasico\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/es\/product\/art-26600-26608-perno-solenoide-de-seguridad-para-enclavamiento\/#listItem","name":"Art. 26600 \/ 26608 &#8211; Elettropistone di sicurezza orizzontale per interblocco &#8211; Aperto in assenza di corrente"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/es\/product-category\/serie-clasica\/#listItem","name":"Serie Classica"}},{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/es\/product\/art-26600-26608-perno-solenoide-de-seguridad-para-enclavamiento\/#listItem","position":5,"name":"Art. 26600 \/ 26608 &#8211; Elettropistone di sicurezza orizzontale per interblocco &#8211; Aperto in assenza di corrente","previousItem":{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/es\/product-category\/serie-clasica\/clasico\/#listItem","name":"Classica"}}]},{"@type":"ItemPage","@id":"https:\/\/www.opera-access.it\/es\/product\/art-26600-26608-perno-solenoide-de-seguridad-para-enclavamiento\/#itempage","url":"https:\/\/www.opera-access.it\/es\/product\/art-26600-26608-perno-solenoide-de-seguridad-para-enclavamiento\/","name":"Art. 26600 \/ 26608 \u2013 Elettropistone di sicurezza orizzontale per interblocco \u2013 Aperto in assenza di corrente - Opera - Operating Access","description":"Elettropistone di sicurezza da fascia per uso intensivo e continuativo, con inserimento sull'anta, per porte in alluminio o acciaio in configurazione singola (condomini, uffici, aziende...) o interbloccate (banche, gioiellerie, enti...), abbinabile a citofoni e a sistemi per controllo accessi. Frontale e contropiastra in acciaio inox (con contropiastra dotata di magnete di allineamento) e catenaccio rotante in acciaio temprato antitaglio e antieffrazione, con blocco meccanico in posizione di chiusura. Aperto in assenza di alimentazione. \u00c8 dotato di elettronica di gestione interna a microprocessore e connettore ad innesto rapido per il collegamento, apertura meccanica con cilindro europeo o maniglia e richiusura automatica con temporizzazioni regolabili (le temporizzazioni sono disinseribili per l\u2019utilizzo dell\u2019elettropistone con elettroniche di gestione esterne). N.B.: il cilindro sagomato a profilo europeo \u00e8 acquistabile separatamente.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.opera-access.it\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.opera-access.it\/es\/product\/art-26600-26608-perno-solenoide-de-seguridad-para-enclavamiento\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.opera-access.it\/wp-content\/uploads\/2025\/03\/27600.jpg","@id":"https:\/\/www.opera-access.it\/es\/product\/art-26600-26608-perno-solenoide-de-seguridad-para-enclavamiento\/#mainImage","width":1200,"height":1000},"primaryImageOfPage":{"@id":"https:\/\/www.opera-access.it\/es\/product\/art-26600-26608-perno-solenoide-de-seguridad-para-enclavamiento\/#mainImage"},"datePublished":"2025-03-24T10:34:16+00:00","dateModified":"2025-10-02T13:08:19+00:00"},{"@type":"Organization","@id":"https:\/\/www.opera-access.it\/es\/#organization","name":"Opera - Operating Access","description":"Elettroserrature, serrature motorizzate, fermi elettromagnetici, controllo accessi","url":"https:\/\/www.opera-access.it\/es\/","logo":{"@type":"ImageObject","url":"https:\/\/www.opera-access.it\/wp-content\/uploads\/2024\/04\/OPERA_logo_WEB.svg","@id":"https:\/\/www.opera-access.it\/es\/product\/art-26600-26608-perno-solenoide-de-seguridad-para-enclavamiento\/#organizationLogo","width":674,"height":172},"image":{"@id":"https:\/\/www.opera-access.it\/es\/product\/art-26600-26608-perno-solenoide-de-seguridad-para-enclavamiento\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/opera.elettroserrature\/","https:\/\/www.instagram.com\/operasrl_italy\/","https:\/\/www.youtube.com\/channel\/UCqDsBsvzX9q1PVTLxOfCm-A\/videos?view_as=subscriber","https:\/\/www.linkedin.com\/company\/opera---locks\/?viewAsMember=true"]},{"@type":"WebSite","@id":"https:\/\/www.opera-access.it\/es\/#website","url":"https:\/\/www.opera-access.it\/es\/","name":"Opera - Operating Access","description":"Elettroserrature, serrature motorizzate, fermi elettromagnetici, controllo accessi","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.opera-access.it\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Opera - Operating Access - Elettroserrature, serrature motorizzate, fermi elettromagnetici, controllo accessi","og:type":"article","og:title":"Art. 26600 \/ 26608 \u2013 Elettropistone di sicurezza orizzontale per interblocco \u2013 Aperto in assenza di corrente - Opera - Operating Access","og:description":"Elettropistone di sicurezza da fascia per uso intensivo e continuativo, con inserimento sull'anta, per porte in alluminio o acciaio in configurazione singola (condomini, uffici, aziende...) o interbloccate (banche, gioiellerie, enti...), abbinabile a citofoni e a sistemi per controllo accessi. Frontale e contropiastra in acciaio inox (con contropiastra dotata di magnete di allineamento) e catenaccio rotante in acciaio temprato antitaglio e antieffrazione, con blocco meccanico in posizione di chiusura. Aperto in assenza di alimentazione. \u00c8 dotato di elettronica di gestione interna a microprocessore e connettore ad innesto rapido per il collegamento, apertura meccanica con cilindro europeo o maniglia e richiusura automatica con temporizzazioni regolabili (le temporizzazioni sono disinseribili per l\u2019utilizzo dell\u2019elettropistone con elettroniche di gestione esterne). N.B.: il cilindro sagomato a profilo europeo \u00e8 acquistabile separatamente.","og:url":"https:\/\/www.opera-access.it\/es\/product\/art-26600-26608-perno-solenoide-de-seguridad-para-enclavamiento\/","og:image":"https:\/\/www.opera-access.it\/wp-content\/uploads\/2024\/04\/RED_8497.jpg","og:image:secure_url":"https:\/\/www.opera-access.it\/wp-content\/uploads\/2024\/04\/RED_8497.jpg","og:image:width":1920,"og:image:height":1280,"article:published_time":"2025-03-24T10:34:16+00:00","article:modified_time":"2025-10-02T13:08:19+00:00","article:publisher":"https:\/\/www.facebook.com\/opera.elettroserrature\/","twitter:card":"summary_large_image","twitter:title":"Art. 26600 \/ 26608 \u2013 Elettropistone di sicurezza orizzontale per interblocco \u2013 Aperto in assenza di corrente - Opera - Operating Access","twitter:description":"Elettropistone di sicurezza da fascia per uso intensivo e continuativo, con inserimento sull'anta, per porte in alluminio o acciaio in configurazione singola (condomini, uffici, aziende...) o interbloccate (banche, gioiellerie, enti...), abbinabile a citofoni e a sistemi per controllo accessi. Frontale e contropiastra in acciaio inox (con contropiastra dotata di magnete di allineamento) e catenaccio rotante in acciaio temprato antitaglio e antieffrazione, con blocco meccanico in posizione di chiusura. Aperto in assenza di alimentazione. \u00c8 dotato di elettronica di gestione interna a microprocessore e connettore ad innesto rapido per il collegamento, apertura meccanica con cilindro europeo o maniglia e richiusura automatica con temporizzazioni regolabili (le temporizzazioni sono disinseribili per l\u2019utilizzo dell\u2019elettropistone con elettroniche di gestione esterne). N.B.: il cilindro sagomato a profilo europeo \u00e8 acquistabile separatamente.","twitter:image":"https:\/\/www.opera-access.it\/wp-content\/uploads\/2024\/04\/RED_8497.jpg"},"aioseo_meta_data":{"post_id":"8027","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-06-09 14:38:24","updated":"2025-10-02 13:19:34","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.opera-access.it\/es\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.opera-access.it\/es\/tienda\/\" title=\"Shop\">Shop<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.opera-access.it\/es\/product-category\/serie-clasica\/\" title=\"Serie Classica\">Serie Classica<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.opera-access.it\/es\/product-category\/serie-clasica\/clasico\/\" title=\"Classica\">Classica<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tArt. 26600 \/ 26608 \u2013 Elettropistone di sicurezza orizzontale per interblocco \u2013 Aperto in assenza di corrente\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.opera-access.it\/es"},{"label":"Shop","link":"https:\/\/www.opera-access.it\/es\/tienda\/"},{"label":"Serie Classica","link":"https:\/\/www.opera-access.it\/es\/product-category\/serie-clasica\/"},{"label":"Classica","link":"https:\/\/www.opera-access.it\/es\/product-category\/serie-clasica\/clasico\/"},{"label":"Art. 26600 \/ 26608 &#8211; Elettropistone di sicurezza orizzontale per interblocco &#8211; Aperto in assenza di corrente","link":"https:\/\/www.opera-access.it\/es\/product\/art-26600-26608-perno-solenoide-de-seguridad-para-enclavamiento\/"}],"_links":{"self":[{"href":"https:\/\/www.opera-access.it\/es\/wp-json\/wp\/v2\/product\/8027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opera-access.it\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.opera-access.it\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opera-access.it\/es\/wp-json\/wp\/v2\/media\/8131"}],"wp:attachment":[{"href":"https:\/\/www.opera-access.it\/es\/wp-json\/wp\/v2\/media?parent=8027"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.opera-access.it\/es\/wp-json\/wp\/v2\/product_cat?post=8027"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.opera-access.it\/es\/wp-json\/wp\/v2\/product_tag?post=8027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}