{"id":7441,"date":"2025-03-19T09:17:24","date_gmt":"2025-03-19T09:17:24","guid":{"rendered":"https:\/\/opera.krescendo.it\/?post_type=product&#038;p=7441"},"modified":"2025-03-20T07:38:53","modified_gmt":"2025-03-20T07:38:53","slug":"art-cc090-replacement-connector","status":"publish","type":"product","link":"https:\/\/www.opera-access.it\/en\/product-2\/art-cc090-replacement-connector\/","title":{"rendered":"Art. CC090 - Spare Connector"},"content":{"rendered":"<p>9-wire connector [<strong>CC090<\/strong>].<\/p>","protected":false},"excerpt":{"rendered":"<p>9-wire replacement connector for Series 256 - 258 - 259 - 278 - 279 and Series OP.<\/p>","protected":false},"featured_media":7549,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_cat":[157,156,27,28],"product_tag":[],"class_list":["post-7441","product","type-product","status-publish","has-post-thumbnail","product_cat-accessori-serie-classica","product_cat-accessori-serie-prima","product_cat-serie-prima","product_cat-serie-classica","first","instock","featured","shipping-taxable","product-type-simple"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Connettore di ricambio a 9 fili per serie 256 - 258 - 259 - 278 - 279 e Serie OP.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.opera-access.it\/en\/product-2\/art-cc090-replacement-connector\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_GB\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Opera - Operating Access - Elettroserrature, serrature motorizzate, fermi elettromagnetici, controllo accessi\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Art. CC090 \u2013 Connettore di ricambio - Opera - Operating Access\" \/>\n\t\t<meta property=\"og:description\" content=\"Connettore di ricambio a 9 fili per serie 256 - 258 - 259 - 278 - 279 e Serie OP.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.opera-access.it\/en\/product-2\/art-cc090-replacement-connector\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.opera-access.it\/wp-content\/uploads\/2024\/04\/RED_8497.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.opera-access.it\/wp-content\/uploads\/2024\/04\/RED_8497.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-03-19T09:17:24+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-03-20T07:38:53+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/opera.elettroserrature\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Art. CC090 \u2013 Connettore di ricambio - Opera - Operating Access\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Connettore di ricambio a 9 fili per serie 256 - 258 - 259 - 278 - 279 e Serie OP.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.opera-access.it\/wp-content\/uploads\/2024\/04\/RED_8497.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/product-2\\\/art-cc090-replacement-connector\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.opera-access.it\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/shop\\\/#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/shop\\\/#listItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/shop\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/product-category\\\/classic-series\\\/#listItem\",\"name\":\"Serie Classica\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/product-category\\\/classic-series\\\/#listItem\",\"position\":3,\"name\":\"Serie Classica\",\"item\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/product-category\\\/classic-series\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/product-category\\\/classic-series\\\/accessories-classic-series\\\/#listItem\",\"name\":\"Accessori\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/shop\\\/#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/product-category\\\/classic-series\\\/accessories-classic-series\\\/#listItem\",\"position\":4,\"name\":\"Accessori\",\"item\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/product-category\\\/classic-series\\\/accessories-classic-series\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/product-2\\\/art-cc090-replacement-connector\\\/#listItem\",\"name\":\"Art. CC090 &#8211; Connettore di ricambio\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/product-category\\\/classic-series\\\/#listItem\",\"name\":\"Serie Classica\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/product-2\\\/art-cc090-replacement-connector\\\/#listItem\",\"position\":5,\"name\":\"Art. CC090 &#8211; Connettore di ricambio\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/product-category\\\/classic-series\\\/accessories-classic-series\\\/#listItem\",\"name\":\"Accessori\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/product-2\\\/art-cc090-replacement-connector\\\/#itempage\",\"url\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/product-2\\\/art-cc090-replacement-connector\\\/\",\"name\":\"Art. CC090 \\u2013 Connettore di ricambio - Opera - Operating Access\",\"description\":\"Connettore di ricambio a 9 fili per serie 256 - 258 - 259 - 278 - 279 e Serie OP.\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/product-2\\\/art-cc090-replacement-connector\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.opera-access.it\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/CC090.jpg\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/product-2\\\/art-cc090-replacement-connector\\\/#mainImage\",\"width\":1200,\"height\":1000},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/product-2\\\/art-cc090-replacement-connector\\\/#mainImage\"},\"datePublished\":\"2025-03-19T09:17:24+00:00\",\"dateModified\":\"2025-03-20T07:38:53+00:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/#organization\",\"name\":\"Opera - Operating Access\",\"description\":\"Elettroserrature, serrature motorizzate, fermi elettromagnetici, controllo accessi\",\"url\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.opera-access.it\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/OPERA_logo_WEB.svg\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/product-2\\\/art-cc090-replacement-connector\\\/#organizationLogo\",\"width\":674,\"height\":172},\"image\":{\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/product-2\\\/art-cc090-replacement-connector\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/opera.elettroserrature\\\/\",\"https:\\\/\\\/www.instagram.com\\\/operasrl_italy\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCqDsBsvzX9q1PVTLxOfCm-A\\\/videos?view_as=subscriber\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/opera---locks\\\/?viewAsMember=true\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/\",\"name\":\"Opera - Operating Access\",\"description\":\"Elettroserrature, serrature motorizzate, fermi elettromagnetici, controllo accessi\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Art. CC090 \u2013 Connettore di ricambio - Opera - Operating Access","description":"Connettore di ricambio a 9 fili per serie 256 - 258 - 259 - 278 - 279 e Serie OP.","canonical_url":"https:\/\/www.opera-access.it\/en\/product-2\/art-cc090-replacement-connector\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.opera-access.it\/en\/product-2\/art-cc090-replacement-connector\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/en#listItem","position":1,"name":"Home","item":"https:\/\/www.opera-access.it\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/en\/shop\/#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/en\/shop\/#listItem","position":2,"name":"Shop","item":"https:\/\/www.opera-access.it\/en\/shop\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/en\/product-category\/classic-series\/#listItem","name":"Serie Classica"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/en\/product-category\/classic-series\/#listItem","position":3,"name":"Serie Classica","item":"https:\/\/www.opera-access.it\/en\/product-category\/classic-series\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/en\/product-category\/classic-series\/accessories-classic-series\/#listItem","name":"Accessori"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/en\/shop\/#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/en\/product-category\/classic-series\/accessories-classic-series\/#listItem","position":4,"name":"Accessori","item":"https:\/\/www.opera-access.it\/en\/product-category\/classic-series\/accessories-classic-series\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/en\/product-2\/art-cc090-replacement-connector\/#listItem","name":"Art. CC090 &#8211; Connettore di ricambio"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/en\/product-category\/classic-series\/#listItem","name":"Serie Classica"}},{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/en\/product-2\/art-cc090-replacement-connector\/#listItem","position":5,"name":"Art. CC090 &#8211; Connettore di ricambio","previousItem":{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/en\/product-category\/classic-series\/accessories-classic-series\/#listItem","name":"Accessori"}}]},{"@type":"ItemPage","@id":"https:\/\/www.opera-access.it\/en\/product-2\/art-cc090-replacement-connector\/#itempage","url":"https:\/\/www.opera-access.it\/en\/product-2\/art-cc090-replacement-connector\/","name":"Art. CC090 \u2013 Connettore di ricambio - Opera - Operating Access","description":"Connettore di ricambio a 9 fili per serie 256 - 258 - 259 - 278 - 279 e Serie OP.","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/www.opera-access.it\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.opera-access.it\/en\/product-2\/art-cc090-replacement-connector\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.opera-access.it\/wp-content\/uploads\/2025\/03\/CC090.jpg","@id":"https:\/\/www.opera-access.it\/en\/product-2\/art-cc090-replacement-connector\/#mainImage","width":1200,"height":1000},"primaryImageOfPage":{"@id":"https:\/\/www.opera-access.it\/en\/product-2\/art-cc090-replacement-connector\/#mainImage"},"datePublished":"2025-03-19T09:17:24+00:00","dateModified":"2025-03-20T07:38:53+00:00"},{"@type":"Organization","@id":"https:\/\/www.opera-access.it\/en\/#organization","name":"Opera - Operating Access","description":"Elettroserrature, serrature motorizzate, fermi elettromagnetici, controllo accessi","url":"https:\/\/www.opera-access.it\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/www.opera-access.it\/wp-content\/uploads\/2024\/04\/OPERA_logo_WEB.svg","@id":"https:\/\/www.opera-access.it\/en\/product-2\/art-cc090-replacement-connector\/#organizationLogo","width":674,"height":172},"image":{"@id":"https:\/\/www.opera-access.it\/en\/product-2\/art-cc090-replacement-connector\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/opera.elettroserrature\/","https:\/\/www.instagram.com\/operasrl_italy\/","https:\/\/www.youtube.com\/channel\/UCqDsBsvzX9q1PVTLxOfCm-A\/videos?view_as=subscriber","https:\/\/www.linkedin.com\/company\/opera---locks\/?viewAsMember=true"]},{"@type":"WebSite","@id":"https:\/\/www.opera-access.it\/en\/#website","url":"https:\/\/www.opera-access.it\/en\/","name":"Opera - Operating Access","description":"Elettroserrature, serrature motorizzate, fermi elettromagnetici, controllo accessi","inLanguage":"en-GB","publisher":{"@id":"https:\/\/www.opera-access.it\/en\/#organization"}}]},"og:locale":"en_GB","og:site_name":"Opera - Operating Access - Elettroserrature, serrature motorizzate, fermi elettromagnetici, controllo accessi","og:type":"article","og:title":"Art. CC090 \u2013 Connettore di ricambio - Opera - Operating Access","og:description":"Connettore di ricambio a 9 fili per serie 256 - 258 - 259 - 278 - 279 e Serie OP.","og:url":"https:\/\/www.opera-access.it\/en\/product-2\/art-cc090-replacement-connector\/","og:image":"https:\/\/www.opera-access.it\/wp-content\/uploads\/2024\/04\/RED_8497.jpg","og:image:secure_url":"https:\/\/www.opera-access.it\/wp-content\/uploads\/2024\/04\/RED_8497.jpg","og:image:width":1920,"og:image:height":1280,"article:published_time":"2025-03-19T09:17:24+00:00","article:modified_time":"2025-03-20T07:38:53+00:00","article:publisher":"https:\/\/www.facebook.com\/opera.elettroserrature\/","twitter:card":"summary_large_image","twitter:title":"Art. CC090 \u2013 Connettore di ricambio - Opera - Operating Access","twitter:description":"Connettore di ricambio a 9 fili per serie 256 - 258 - 259 - 278 - 279 e Serie OP.","twitter:image":"https:\/\/www.opera-access.it\/wp-content\/uploads\/2024\/04\/RED_8497.jpg"},"aioseo_meta_data":{"post_id":"7441","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-06-09 14:37:15","updated":"2025-06-09 14:37:15","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.opera-access.it\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.opera-access.it\/en\/shop\/\" title=\"Shop\">Shop<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.opera-access.it\/en\/product-category\/classic-series\/\" title=\"Serie Classica\">Serie Classica<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.opera-access.it\/en\/product-category\/classic-series\/accessories-classic-series\/\" title=\"Accessori\">Accessori<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tArt. CC090 \u2013 Connettore di ricambio\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.opera-access.it\/en"},{"label":"Shop","link":"https:\/\/www.opera-access.it\/en\/shop\/"},{"label":"Serie Classica","link":"https:\/\/www.opera-access.it\/en\/product-category\/classic-series\/"},{"label":"Accessori","link":"https:\/\/www.opera-access.it\/en\/product-category\/classic-series\/accessories-classic-series\/"},{"label":"Art. CC090 &#8211; Connettore di ricambio","link":"https:\/\/www.opera-access.it\/en\/product-2\/art-cc090-replacement-connector\/"}],"_links":{"self":[{"href":"https:\/\/www.opera-access.it\/en\/wp-json\/wp\/v2\/product\/7441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opera-access.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.opera-access.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opera-access.it\/en\/wp-json\/wp\/v2\/media\/7549"}],"wp:attachment":[{"href":"https:\/\/www.opera-access.it\/en\/wp-json\/wp\/v2\/media?parent=7441"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.opera-access.it\/en\/wp-json\/wp\/v2\/product_cat?post=7441"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.opera-access.it\/en\/wp-json\/wp\/v2\/product_tag?post=7441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}