{"id":1952,"date":"2025-01-16T15:21:08","date_gmt":"2025-01-16T15:21:08","guid":{"rendered":"https:\/\/opera.krescendo.it\/?post_type=product&#038;p=1952"},"modified":"2025-06-27T13:57:05","modified_gmt":"2025-06-27T13:57:05","slug":"03007-glass-mounting-bracket-for-series-136-and-137","status":"publish","type":"product","link":"https:\/\/www.opera-access.it\/en\/product-2\/03007-glass-mounting-bracket-for-series-136-and-137\/","title":{"rendered":"Art. 03007 - 'U' mounting bracket for 'Glass' counterplate for series 136 - 137"},"content":{"rendered":"<p>Bracket in steel and silver anodised aluminium. Article code: [<strong>03007<\/strong>].<\/p>","protected":false},"excerpt":{"rendered":"<p>Bracket for fixing the armature plate of electromagnets series 136 and 137 on glass doors.<\/p>","protected":false},"featured_media":1953,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_cat":[37,21],"product_tag":[],"class_list":["post-1952","product","type-product","status-publish","has-post-thumbnail","product_cat-accessori-serie-safety","product_cat-serie-safety","first","instock","featured","shipping-taxable","product-type-simple"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Staffa per il fissaggio della contropiastra degli elettromagneti serie 136 e 137 su porte in cristallo.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.opera-access.it\/en\/product-2\/03007-glass-mounting-bracket-for-series-136-and-137\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_GB\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Opera - Operating Access - Elettroserrature, serrature motorizzate, fermi elettromagnetici, controllo accessi\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Art. 03007 \u2013 Staffa di montaggio a \u201cU\u201d per contropiastra a \u201cVetro\u201d per serie 136 \u2013 137 - Opera - Operating Access\" \/>\n\t\t<meta property=\"og:description\" content=\"Staffa per il fissaggio della contropiastra degli elettromagneti serie 136 e 137 su porte in cristallo.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.opera-access.it\/en\/product-2\/03007-glass-mounting-bracket-for-series-136-and-137\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.opera-access.it\/wp-content\/uploads\/2024\/04\/RED_8497.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.opera-access.it\/wp-content\/uploads\/2024\/04\/RED_8497.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-01-16T15:21:08+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-06-27T13:57:05+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/opera.elettroserrature\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Art. 03007 \u2013 Staffa di montaggio a \u201cU\u201d per contropiastra a \u201cVetro\u201d per serie 136 \u2013 137 - Opera - Operating Access\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Staffa per il fissaggio della contropiastra degli elettromagneti serie 136 e 137 su porte in cristallo.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.opera-access.it\/wp-content\/uploads\/2024\/04\/RED_8497.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/product-2\\\/03007-glass-mounting-bracket-for-series-136-and-137\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.opera-access.it\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/shop\\\/#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/shop\\\/#listItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/shop\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/product-category\\\/safety-series\\\/#listItem\",\"name\":\"Serie Safety\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/product-category\\\/safety-series\\\/#listItem\",\"position\":3,\"name\":\"Serie Safety\",\"item\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/product-category\\\/safety-series\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/product-category\\\/safety-series\\\/safety-series-accessories\\\/#listItem\",\"name\":\"Accessori\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/shop\\\/#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/product-category\\\/safety-series\\\/safety-series-accessories\\\/#listItem\",\"position\":4,\"name\":\"Accessori\",\"item\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/product-category\\\/safety-series\\\/safety-series-accessories\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/product-2\\\/03007-glass-mounting-bracket-for-series-136-and-137\\\/#listItem\",\"name\":\"Art. 03007 &#8211; Staffa di montaggio a &#8220;U&#8221; per contropiastra a &#8220;Vetro&#8221; per serie 136 &#8211; 137\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/product-category\\\/safety-series\\\/#listItem\",\"name\":\"Serie Safety\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/product-2\\\/03007-glass-mounting-bracket-for-series-136-and-137\\\/#listItem\",\"position\":5,\"name\":\"Art. 03007 &#8211; Staffa di montaggio a &#8220;U&#8221; per contropiastra a &#8220;Vetro&#8221; per serie 136 &#8211; 137\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/product-category\\\/safety-series\\\/safety-series-accessories\\\/#listItem\",\"name\":\"Accessori\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/product-2\\\/03007-glass-mounting-bracket-for-series-136-and-137\\\/#itempage\",\"url\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/product-2\\\/03007-glass-mounting-bracket-for-series-136-and-137\\\/\",\"name\":\"Art. 03007 \\u2013 Staffa di montaggio a \\u201cU\\u201d per contropiastra a \\u201cVetro\\u201d per serie 136 \\u2013 137 - Opera - Operating Access\",\"description\":\"Staffa per il fissaggio della contropiastra degli elettromagneti serie 136 e 137 su porte in cristallo.\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/product-2\\\/03007-glass-mounting-bracket-for-series-136-and-137\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.opera-access.it\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/03007.jpg\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/product-2\\\/03007-glass-mounting-bracket-for-series-136-and-137\\\/#mainImage\",\"width\":1200,\"height\":1000},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/product-2\\\/03007-glass-mounting-bracket-for-series-136-and-137\\\/#mainImage\"},\"datePublished\":\"2025-01-16T15:21:08+00:00\",\"dateModified\":\"2025-06-27T13:57:05+00:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/#organization\",\"name\":\"Opera - Operating Access\",\"description\":\"Elettroserrature, serrature motorizzate, fermi elettromagnetici, controllo accessi\",\"url\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.opera-access.it\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/OPERA_logo_WEB.svg\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/product-2\\\/03007-glass-mounting-bracket-for-series-136-and-137\\\/#organizationLogo\",\"width\":674,\"height\":172},\"image\":{\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/product-2\\\/03007-glass-mounting-bracket-for-series-136-and-137\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/opera.elettroserrature\\\/\",\"https:\\\/\\\/www.instagram.com\\\/operasrl_italy\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCqDsBsvzX9q1PVTLxOfCm-A\\\/videos?view_as=subscriber\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/opera---locks\\\/?viewAsMember=true\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/\",\"name\":\"Opera - Operating Access\",\"description\":\"Elettroserrature, serrature motorizzate, fermi elettromagnetici, controllo accessi\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.opera-access.it\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Art. 03007 \u2013 Staffa di montaggio a \u201cU\u201d per contropiastra a \u201cVetro\u201d per serie 136 \u2013 137 - Opera - Operating Access","description":"Staffa per il fissaggio della contropiastra degli elettromagneti serie 136 e 137 su porte in cristallo.","canonical_url":"https:\/\/www.opera-access.it\/en\/product-2\/03007-glass-mounting-bracket-for-series-136-and-137\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.opera-access.it\/en\/product-2\/03007-glass-mounting-bracket-for-series-136-and-137\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/en#listItem","position":1,"name":"Home","item":"https:\/\/www.opera-access.it\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/en\/shop\/#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/en\/shop\/#listItem","position":2,"name":"Shop","item":"https:\/\/www.opera-access.it\/en\/shop\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/en\/product-category\/safety-series\/#listItem","name":"Serie Safety"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/en\/product-category\/safety-series\/#listItem","position":3,"name":"Serie Safety","item":"https:\/\/www.opera-access.it\/en\/product-category\/safety-series\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/en\/product-category\/safety-series\/safety-series-accessories\/#listItem","name":"Accessori"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/en\/shop\/#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/en\/product-category\/safety-series\/safety-series-accessories\/#listItem","position":4,"name":"Accessori","item":"https:\/\/www.opera-access.it\/en\/product-category\/safety-series\/safety-series-accessories\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/en\/product-2\/03007-glass-mounting-bracket-for-series-136-and-137\/#listItem","name":"Art. 03007 &#8211; Staffa di montaggio a &#8220;U&#8221; per contropiastra a &#8220;Vetro&#8221; per serie 136 &#8211; 137"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/en\/product-category\/safety-series\/#listItem","name":"Serie Safety"}},{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/en\/product-2\/03007-glass-mounting-bracket-for-series-136-and-137\/#listItem","position":5,"name":"Art. 03007 &#8211; Staffa di montaggio a &#8220;U&#8221; per contropiastra a &#8220;Vetro&#8221; per serie 136 &#8211; 137","previousItem":{"@type":"ListItem","@id":"https:\/\/www.opera-access.it\/en\/product-category\/safety-series\/safety-series-accessories\/#listItem","name":"Accessori"}}]},{"@type":"ItemPage","@id":"https:\/\/www.opera-access.it\/en\/product-2\/03007-glass-mounting-bracket-for-series-136-and-137\/#itempage","url":"https:\/\/www.opera-access.it\/en\/product-2\/03007-glass-mounting-bracket-for-series-136-and-137\/","name":"Art. 03007 \u2013 Staffa di montaggio a \u201cU\u201d per contropiastra a \u201cVetro\u201d per serie 136 \u2013 137 - Opera - Operating Access","description":"Staffa per il fissaggio della contropiastra degli elettromagneti serie 136 e 137 su porte in cristallo.","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/www.opera-access.it\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.opera-access.it\/en\/product-2\/03007-glass-mounting-bracket-for-series-136-and-137\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.opera-access.it\/wp-content\/uploads\/2025\/01\/03007.jpg","@id":"https:\/\/www.opera-access.it\/en\/product-2\/03007-glass-mounting-bracket-for-series-136-and-137\/#mainImage","width":1200,"height":1000},"primaryImageOfPage":{"@id":"https:\/\/www.opera-access.it\/en\/product-2\/03007-glass-mounting-bracket-for-series-136-and-137\/#mainImage"},"datePublished":"2025-01-16T15:21:08+00:00","dateModified":"2025-06-27T13:57:05+00:00"},{"@type":"Organization","@id":"https:\/\/www.opera-access.it\/en\/#organization","name":"Opera - Operating Access","description":"Elettroserrature, serrature motorizzate, fermi elettromagnetici, controllo accessi","url":"https:\/\/www.opera-access.it\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/www.opera-access.it\/wp-content\/uploads\/2024\/04\/OPERA_logo_WEB.svg","@id":"https:\/\/www.opera-access.it\/en\/product-2\/03007-glass-mounting-bracket-for-series-136-and-137\/#organizationLogo","width":674,"height":172},"image":{"@id":"https:\/\/www.opera-access.it\/en\/product-2\/03007-glass-mounting-bracket-for-series-136-and-137\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/opera.elettroserrature\/","https:\/\/www.instagram.com\/operasrl_italy\/","https:\/\/www.youtube.com\/channel\/UCqDsBsvzX9q1PVTLxOfCm-A\/videos?view_as=subscriber","https:\/\/www.linkedin.com\/company\/opera---locks\/?viewAsMember=true"]},{"@type":"WebSite","@id":"https:\/\/www.opera-access.it\/en\/#website","url":"https:\/\/www.opera-access.it\/en\/","name":"Opera - Operating Access","description":"Elettroserrature, serrature motorizzate, fermi elettromagnetici, controllo accessi","inLanguage":"en-GB","publisher":{"@id":"https:\/\/www.opera-access.it\/en\/#organization"}}]},"og:locale":"en_GB","og:site_name":"Opera - Operating Access - Elettroserrature, serrature motorizzate, fermi elettromagnetici, controllo accessi","og:type":"article","og:title":"Art. 03007 \u2013 Staffa di montaggio a \u201cU\u201d per contropiastra a \u201cVetro\u201d per serie 136 \u2013 137 - Opera - Operating Access","og:description":"Staffa per il fissaggio della contropiastra degli elettromagneti serie 136 e 137 su porte in cristallo.","og:url":"https:\/\/www.opera-access.it\/en\/product-2\/03007-glass-mounting-bracket-for-series-136-and-137\/","og:image":"https:\/\/www.opera-access.it\/wp-content\/uploads\/2024\/04\/RED_8497.jpg","og:image:secure_url":"https:\/\/www.opera-access.it\/wp-content\/uploads\/2024\/04\/RED_8497.jpg","og:image:width":1920,"og:image:height":1280,"article:published_time":"2025-01-16T15:21:08+00:00","article:modified_time":"2025-06-27T13:57:05+00:00","article:publisher":"https:\/\/www.facebook.com\/opera.elettroserrature\/","twitter:card":"summary_large_image","twitter:title":"Art. 03007 \u2013 Staffa di montaggio a \u201cU\u201d per contropiastra a \u201cVetro\u201d per serie 136 \u2013 137 - Opera - Operating Access","twitter:description":"Staffa per il fissaggio della contropiastra degli elettromagneti serie 136 e 137 su porte in cristallo.","twitter:image":"https:\/\/www.opera-access.it\/wp-content\/uploads\/2024\/04\/RED_8497.jpg"},"aioseo_meta_data":{"post_id":"1952","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"ItemPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-06-09 14:18:23","updated":"2025-06-27 14:06:17","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.opera-access.it\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.opera-access.it\/en\/shop\/\" title=\"Shop\">Shop<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.opera-access.it\/en\/product-category\/safety-series\/\" title=\"Serie Safety\">Serie Safety<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.opera-access.it\/en\/product-category\/safety-series\/safety-series-accessories\/\" title=\"Accessori\">Accessori<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tArt. 03007 \u2013 Staffa di montaggio a \u201cU\u201d per contropiastra a \u201cVetro\u201d per serie 136 \u2013 137\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.opera-access.it\/en"},{"label":"Shop","link":"https:\/\/www.opera-access.it\/en\/shop\/"},{"label":"Serie Safety","link":"https:\/\/www.opera-access.it\/en\/product-category\/safety-series\/"},{"label":"Accessori","link":"https:\/\/www.opera-access.it\/en\/product-category\/safety-series\/safety-series-accessories\/"},{"label":"Art. 03007 &#8211; Staffa di montaggio a &#8220;U&#8221; per contropiastra a &#8220;Vetro&#8221; per serie 136 &#8211; 137","link":"https:\/\/www.opera-access.it\/en\/product-2\/03007-glass-mounting-bracket-for-series-136-and-137\/"}],"_links":{"self":[{"href":"https:\/\/www.opera-access.it\/en\/wp-json\/wp\/v2\/product\/1952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opera-access.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.opera-access.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opera-access.it\/en\/wp-json\/wp\/v2\/media\/1953"}],"wp:attachment":[{"href":"https:\/\/www.opera-access.it\/en\/wp-json\/wp\/v2\/media?parent=1952"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.opera-access.it\/en\/wp-json\/wp\/v2\/product_cat?post=1952"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.opera-access.it\/en\/wp-json\/wp\/v2\/product_tag?post=1952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}